{"id":20508,"date":"2023-02-17T15:07:52","date_gmt":"2023-02-17T13:07:52","guid":{"rendered":"https:\/\/store.djicyprus.com\/?post_type=product&#038;p=20508"},"modified":"2026-07-01T21:08:58","modified_gmt":"2026-07-01T18:08:58","slug":"dji-mini-3-dji-rc","status":"publish","type":"product","link":"https:\/\/dronehouse.gr\/en\/product\/dji-mini-3-dji-rc\/","title":{"rendered":"DJI Mini 3 (DJI RC)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20145\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/1-1024x443.png\" alt=\"\" width=\"1024\" height=\"443\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/1-1024x443.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/1-scaled-150x65.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/1-scaled-1200x519.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/1-300x130.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/1-768x332.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/1-600x260.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/1-1536x665.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/1-2048x886.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/1-640x277.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/1-400x173.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/1-367x159.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/1-570x247.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20146\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/2-1024x435.png\" alt=\"\" width=\"1024\" height=\"435\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/2-1024x435.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/2-scaled-150x64.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/2-scaled-1200x510.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/2-300x127.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/2-768x326.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/2-600x255.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/2-1536x653.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/2-2048x870.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/2-640x272.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/2-400x170.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/2-367x156.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/2-570x242.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20147\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/3-1024x472.jpg\" alt=\"\" width=\"1024\" height=\"472\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/3-1024x472.jpg 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/3-scaled-150x69.jpg 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/3-scaled-1200x553.jpg 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/3-300x138.jpg 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/3-768x354.jpg 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/3-600x276.jpg 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/3-1536x707.jpg 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/3-2048x943.jpg 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/3-640x295.jpg 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/3-400x184.jpg 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/3-367x169.jpg 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/3-570x263.jpg 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20148\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/4-1024x481.png\" alt=\"\" width=\"1024\" height=\"481\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/4-1024x481.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/4-scaled-150x70.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/4-scaled-1200x564.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/4-300x141.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/4-768x361.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/4-600x282.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/4-1536x722.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/4-2048x963.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/4-640x301.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/4-400x188.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/4-367x173.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/4-570x268.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20149\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/5-1024x261.png\" alt=\"\" width=\"1024\" height=\"261\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/5-1024x261.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/5-scaled-150x38.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/5-scaled-1200x307.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/5-300x77.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/5-768x196.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/5-600x153.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/5-1536x392.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/5-2048x523.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/5-640x163.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/5-400x102.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/5-367x94.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/5-570x146.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20150\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/6-1024x485.jpg\" alt=\"\" width=\"1024\" height=\"485\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/6-1024x485.jpg 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/6-scaled-150x71.jpg 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/6-scaled-1200x569.jpg 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/6-300x142.jpg 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/6-768x364.jpg 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/6-600x284.jpg 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/6-1536x728.jpg 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/6-2048x971.jpg 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/6-640x303.jpg 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/6-400x190.jpg 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/6-367x174.jpg 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/6-570x270.jpg 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20151\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/7-1024x243.png\" alt=\"\" width=\"1024\" height=\"243\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/7-1024x243.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/7-scaled-150x36.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/7-scaled-1200x285.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/7-300x71.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/7-768x183.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/7-600x143.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/7-1536x365.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/7-2048x487.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/7-640x152.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/7-400x95.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/7-367x87.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/7-570x136.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20124\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/8-1024x351.png\" alt=\"\" width=\"1024\" height=\"351\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/8-1024x351.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/8-scaled-150x51.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/8-scaled-1200x412.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/8-300x103.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/8-768x263.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/8-600x206.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/8-1536x527.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/8-2048x703.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/8-640x220.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/8-400x137.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/8-367x126.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/8-570x196.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20125\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/9-1024x456.png\" alt=\"\" width=\"1024\" height=\"456\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/9-1024x456.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/9-scaled-150x67.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/9-scaled-1200x535.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/9-300x134.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/9-768x342.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/9-600x267.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/9-1536x684.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/9-2048x912.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/9-640x285.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/9-400x178.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/9-367x164.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/9-570x254.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20126\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/10-1024x419.png\" alt=\"\" width=\"1024\" height=\"419\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/10-1024x419.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/10-scaled-150x61.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/10-scaled-1200x492.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/10-300x123.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/10-768x315.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/10-600x246.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/10-1536x629.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/10-2048x839.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/10-640x262.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/10-400x164.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/10-367x150.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/10-570x233.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20127\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/11-1024x222.png\" alt=\"\" width=\"1024\" height=\"222\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/11-1024x222.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/11-scaled-150x32.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/11-scaled-1200x260.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/11-300x65.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/11-768x166.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/11-600x130.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/11-1536x332.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/11-2048x443.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/11-640x139.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/11-400x87.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/11-367x79.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/11-570x123.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20128\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/12-1024x454.png\" alt=\"\" width=\"1024\" height=\"454\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/12-1024x454.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/12-scaled-150x67.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/12-scaled-1200x532.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/12-300x133.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/12-768x340.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/12-600x266.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/12-1536x681.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/12-2048x908.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/12-640x284.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/12-400x177.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/12-367x163.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/12-570x253.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20130\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/14-1024x350.png\" alt=\"\" width=\"1024\" height=\"350\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/14-1024x350.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/14-scaled-150x51.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/14-scaled-1200x410.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/14-300x103.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/14-768x262.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/14-600x205.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/14-1536x525.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/14-2048x700.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/14-640x219.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/14-400x137.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/14-367x125.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/14-570x195.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20131\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/15-1024x383.png\" alt=\"\" width=\"1024\" height=\"383\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/15-1024x383.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/15-scaled-150x56.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/15-scaled-1200x449.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/15-300x112.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/15-768x287.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/15-600x224.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/15-1536x575.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/15-2048x766.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/15-640x239.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/15-400x150.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/15-367x137.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/15-570x213.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20132\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/16-1024x363.png\" alt=\"\" width=\"1024\" height=\"363\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/16-1024x363.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/16-scaled-150x53.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/16-scaled-1200x425.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/16-300x106.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/16-768x272.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/16-600x213.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/16-1536x544.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/16-2048x726.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/16-640x227.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/16-400x142.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/16-367x130.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/16-570x202.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20133\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/17-1024x339.jpg\" alt=\"\" width=\"1024\" height=\"339\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/17-1024x339.jpg 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/17-scaled-150x50.jpg 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/17-scaled-1200x397.jpg 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/17-300x99.jpg 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/17-768x254.jpg 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/17-600x198.jpg 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/17-1536x508.jpg 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/17-2048x677.jpg 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/17-640x212.jpg 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/17-400x132.jpg 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/17-367x121.jpg 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/17-570x188.jpg 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20134\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/18-1024x379.png\" alt=\"\" width=\"1024\" height=\"379\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/18-1024x379.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/18-scaled-150x56.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/18-scaled-1200x444.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/18-300x111.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/18-768x284.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/18-600x222.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/18-1536x569.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/18-2048x759.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/18-640x237.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/18-400x148.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/18-367x136.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/18-570x211.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20135\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/19-1024x430.png\" alt=\"\" width=\"1024\" height=\"430\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/19-1024x430.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/19-scaled-150x63.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/19-scaled-1200x504.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/19-300x126.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/19-768x322.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/19-600x252.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/19-1536x645.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/19-2048x860.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/19-640x269.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/19-400x168.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/19-367x154.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/19-570x239.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20136\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/20-1024x440.jpg\" alt=\"\" width=\"1024\" height=\"440\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/20-1024x440.jpg 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/20-scaled-150x64.jpg 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/20-scaled-1200x515.jpg 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/20-300x129.jpg 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/20-768x330.jpg 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/20-600x258.jpg 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/20-1536x660.jpg 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/20-2048x879.jpg 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/20-640x275.jpg 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/20-400x172.jpg 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/20-367x158.jpg 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/20-570x245.jpg 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20137\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/21-1024x433.png\" alt=\"\" width=\"1024\" height=\"433\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/21-1024x433.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/21-scaled-150x63.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/21-scaled-1200x507.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/21-300x127.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/21-768x325.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/21-600x254.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/21-1536x649.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/21-2048x866.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/21-640x270.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/21-400x169.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/21-367x155.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/21-570x241.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20138\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/22-1024x322.png\" alt=\"\" width=\"1024\" height=\"322\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/22-1024x322.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/22-scaled-150x47.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/22-scaled-1200x377.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/22-300x94.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/22-768x241.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/22-600x189.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/22-1536x483.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/22-2048x644.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/22-640x201.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/22-400x126.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/22-367x115.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/22-570x179.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20139\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/23-1024x394.png\" alt=\"\" width=\"1024\" height=\"394\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/23-1024x394.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/23-scaled-150x58.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/23-scaled-1200x462.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/23-300x116.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/23-768x296.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/23-600x231.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/23-1536x592.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/23-2048x789.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/23-640x246.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/23-400x154.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/23-367x141.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/23-570x220.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20140\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/24-1024x271.jpg\" alt=\"\" width=\"1024\" height=\"271\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/24-1024x271.jpg 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/24-scaled-150x40.jpg 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/24-scaled-1200x318.jpg 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/24-300x80.jpg 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/24-768x204.jpg 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/24-600x159.jpg 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/24-1536x407.jpg 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/24-2048x543.jpg 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/24-640x170.jpg 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/24-400x106.jpg 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/24-367x97.jpg 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/24-570x151.jpg 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20141\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/25-1024x276.jpg\" alt=\"\" width=\"1024\" height=\"276\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/25-1024x276.jpg 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/25-scaled-150x40.jpg 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/25-scaled-1200x324.jpg 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/25-300x81.jpg 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/25-768x207.jpg 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/25-600x162.jpg 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/25-1536x414.jpg 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/25-2048x553.jpg 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/25-640x173.jpg 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/25-400x108.jpg 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/25-367x99.jpg 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/25-570x154.jpg 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20142\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/26-1024x431.png\" alt=\"\" width=\"1024\" height=\"431\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/26-1024x431.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/26-scaled-150x63.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/26-scaled-1200x505.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/26-300x126.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/26-768x323.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/26-600x252.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/26-1536x646.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/26-2048x861.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/26-640x269.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/26-400x168.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/26-367x154.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/26-570x240.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20143\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/27-1024x338.png\" alt=\"\" width=\"1024\" height=\"338\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/27-1024x338.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/27-scaled-150x49.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/27-scaled-1200x396.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/27-300x99.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/27-768x253.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/27-600x198.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/27-1536x506.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/27-2048x675.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/27-640x211.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/27-400x132.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/27-367x121.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/27-570x188.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20144\" src=\"https:\/\/store.djicyprus.com\/wp-content\/uploads\/2022\/12\/28-1024x412.png\" alt=\"\" width=\"1024\" height=\"412\" srcset=\"https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/28-1024x412.png 1024w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/28-scaled-150x60.png 150w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/28-scaled-1200x483.png 1200w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/28-300x121.png 300w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/28-768x309.png 768w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/28-600x241.png 600w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/28-1536x618.png 1536w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/28-2048x824.png 2048w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/28-640x258.png 640w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/28-400x161.png 400w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/28-367x148.png 367w, https:\/\/dronehouse.gr\/wp-content\/uploads\/2022\/12\/28-570x229.png 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Mini-3-DJIRC<\/p>","protected":false},"featured_media":20109,"template":"","meta":[],"product_brand":[],"product_cat":[2150,2151],"product_tag":[],"class_list":["post-20508","product","type-product","status-publish","has-post-thumbnail","product_cat-mini-3","product_cat-mini-3-drones-combos","first","outofstock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/dronehouse.gr\/en\/wp-json\/wp\/v2\/product\/20508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dronehouse.gr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dronehouse.gr\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/dronehouse.gr\/en\/wp-json\/wp\/v2\/product\/20508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dronehouse.gr\/en\/wp-json\/wp\/v2\/media\/20109"}],"wp:attachment":[{"href":"https:\/\/dronehouse.gr\/en\/wp-json\/wp\/v2\/media?parent=20508"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dronehouse.gr\/en\/wp-json\/wp\/v2\/product_brand?post=20508"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dronehouse.gr\/en\/wp-json\/wp\/v2\/product_cat?post=20508"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dronehouse.gr\/en\/wp-json\/wp\/v2\/product_tag?post=20508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}